{"id":4898,"date":"2011-11-04T16:49:36","date_gmt":"2011-11-04T15:49:36","guid":{"rendered":"http:\/\/www.lacanquotidien.fr\/blog\/?p=4898"},"modified":"2011-11-16T16:51:03","modified_gmt":"2011-11-16T15:51:03","slug":"chemins-de-traverse-2","status":"publish","type":"post","link":"https:\/\/lacanquotidien.fr\/blog\/2011\/11\/chemins-de-traverse-2\/","title":{"rendered":"CHEMINS DE TRAVERSE"},"content":{"rendered":"<p style=\"text-align: center;\" align=\"JUSTIFY\">\u00a0<span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: medium;\"><strong>La mati\u00e8re complexe du pouvoir <span style=\"color: #0000cc;\"><em>par Aur\u00e9lie Pfauwadel<\/em><\/span><\/strong><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: small;\">Deux films, cette semaine au cin\u00e9ma, nous offrent une plong\u00e9e dans les arcanes du pouvoir\u00a0: <span style=\"color: #0000ff;\"><em><strong>Les marches du pouvoir<\/strong><\/em><\/span><span style=\"color: #0000ff;\"><strong>, de George Clonney<\/strong><\/span>, et\u00a0<span style=\"color: #0000ff;\"><em><strong>L\u2019exercice de l\u2019\u00c9tat<\/strong><\/em><\/span><span style=\"color: #0000ff;\"><strong> de Pierre Schoeller<\/strong><\/span>. <!--more--><strong>Les coulisses du pouvoir<\/strong> est un th\u00e8me cin\u00e9matographique tr\u00e8s actuel\u00a0: les r\u00e9cents films <span style=\"color: #0000ff;\"><em><strong>Pater<\/strong><\/em><\/span><span style=\"color: #0000ff;\"><strong> d\u2019Alain Cavalier<\/strong><\/span> et <span style=\"color: #0000ff;\"><em><strong>La Conqu\u00eate<\/strong><\/em><\/span><span style=\"color: #0000ff;\"><strong> de Xavier Durringer<\/strong><\/span> (sur l\u2019irr\u00e9sistible ascension de Nicolas Sarkozy \u00e0 la Pr\u00e9sidence), tous deux sortis en mai 2011, invitaient \u00e9galement les spectateurs \u00e0 voir <strong>l\u2019envers du d\u00e9cor<\/strong>. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><a name=\"_GoBack\"><\/a><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: small;\"><em>Les marches du pouvoir<\/em>, am\u00e9ricain, de facture classique, est un film de strat\u00e9gie, un jeu d\u2019\u00e9chec o\u00f9 les personnages gardent toujours un ou deux coups d\u2019avance sur le spectateur surpris par les retournements.\u00a0Stephen Meyers (jou\u00e9 par le charmant Ryan Gosling) est conseiller de campagne du gouverneur Mike Morris (G. Clooney), candidat \u00e0 la primaire d\u00e9mocrate. Jeune et dou\u00e9 pour la manipulation des m\u00e9dias, il met tout son talent au service de ce candidat qu\u2019il croit sinc\u00e8rement \u00eatre le seul capable de \u00ab\u00a0changer les choses\u00a0\u00bb. Le titre original du film (<em>The Ides of March<\/em>, les \u00ab\u00a0Ides de Mars\u00a0\u00bb) donne un port\u00e9e plus symbolique \u00e0 ce Brutus des temps modernes, pas si traitre que cela. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: small;\"><em>L\u2019exercice de l\u2019\u00c9tat<\/em>, fran\u00e7ais, est plus original\u00a0: la mise en sc\u00e8ne moderne et rythm\u00e9e, les textures sonores, les trouvailles visuelles (tels les SMS surimprim\u00e9s en mode plein \u00e9cran) \u00e9voquent l\u2019inventivit\u00e9 de <span style=\"color: #0000ff;\"><em><strong>Il divo<\/strong><\/em><\/span><span style=\"color: #0000ff;\"><strong>, le film de Paolo Sorrentino<\/strong><\/span> (2008) qui retra\u00e7ait le parcours politique de Giulio Andreotti. Il ne s\u2019agit pas ici d\u2019un film sur la conqu\u00eate du pouvoir, mais sur son exercice effectif. <strong>Qui sont ces hommes qui font fonctionner, au plus haut niveau, ce grand monstre froid qu\u2019est l\u2019\u00c9tat\u00a0?<\/strong> <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: small;\">Ces films \u00e9voquent tous la suspension des hommes politiques aux l\u00e8vres des sondages, et leur ali\u00e9nation au r\u00e8gne de l\u2019image, du marketing et des m\u00e9dias. La politique est un th\u00e9\u00e2tre, certes\u00a0: dans la sc\u00e8ne d\u2019ouverture de <em>L\u2019exercice de l\u2019\u00c9tat<\/em>, des personnages cagoul\u00e9s viennent d\u00e9poser les accessoires caract\u00e9ristiques de son d\u00e9cor. <em>Pater<\/em>, film le plus curieux qui soit, pousse aussi \u00e0 l\u2019extr\u00eame l\u2019id\u00e9e de politique comme jeu, en utilisant la modalit\u00e9 enfantine du \u00ab\u00a0comme si\u00a0\u00bb\u00a0: \u00ab\u00a0on dirait qu\u2019Alain Cavalier serait le Pr\u00e9sident, et Vincent Lindon son Premier ministre\u00a0\u00bb.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: small;\"><strong>Cette primaut\u00e9 du para\u00eetre n\u2019est pas nouvelle\u00a0: elle est constitutive du<\/strong><strong>champ politique.<\/strong> <span style=\"color: #0000ff;\"><strong>Maurice Merleau-Ponty, dans <\/strong><\/span><span style=\"color: #0000ff;\"><em><strong>Signes<\/strong><\/em><\/span><strong> <\/strong>(chapitre X), avait cette notation po\u00e9tique\u00a0\u00e0 propos du <span style=\"color: #0000ff;\"><em><strong>Prince<\/strong><\/em><\/span><span style=\"color: #0000ff;\"><strong> de Machiavel\u00a0<\/strong><\/span>: \u00ab comme des miroirs dispos\u00e9s en cercle transforment une mince flamme en f\u00e9erie, les actes du pouvoir, r\u00e9fl\u00e9chis dans la constellation des consciences, se transfigurent, et les reflets de ces reflets cr\u00e9ent une apparence qui est le lieu propre et en somme la v\u00e9rit\u00e9 de l\u2019action historique. Le pouvoir porte autour de lui un halo, et sa mal\u00e9diction (\u2026) est de ne pas voir l\u2019image de lui-m\u00eame qu\u2019il offre aux autres. C\u2019est donc une condition fondamentale de la politique de se d\u00e9rouler dans l\u2019apparence\u00a0\u00bb.\u00a0 Les \u00ab\u00a0conseillers en communication\u00a0\u00bb sont d\u00e9sormais ceux qui tentent de ma\u00eetriser ce halo m\u00e9diatique du pouvoir.<\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: small;\">Cependant, <strong>cette dimension l\u00e9gendaire, fictionnelle, imaginaire du pouvoir n\u2019est pas tout\u00a0\u2013 voil\u00e0 ce que nous disent ces diff\u00e9rents films<\/strong>. <em>Les marches du pouvoir<\/em> mettent en sc\u00e8ne un Clooney candidat lisse et parfait sous les lumi\u00e8res des shows t\u00e9l\u00e9vis\u00e9s. Mais l\u2019intrigue le met en jeu, lui, en tant qu\u2019homme, et concerne les hommes (et femmes) de l\u2019ombre, leurs rapports d\u2019amiti\u00e9, de loyaut\u00e9 ou de trahison. Tel est le point focal de cette nouvelle vague de films politiques\u00a0: les rapports d\u2019homme \u00e0 homme qui font grincer la grande m\u00e9canique du pouvoir \u2013 ou s\u2019y trouvent broy\u00e9s d\u00e9finitivement. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: small;\">Ainsi, <em>L\u2019exercice de l\u2019\u00c9tat<\/em> n\u2019est pas un film sur la politique, mais sur les gouvernants et leur pratique du pouvoir\u00a0: sur ces hommes qui incarnent l\u2019\u00c9tat et y vouent leur vie. On y suit un ministre des Transports sous pression (Bertrand Saint-Jean, jou\u00e9 par Olivier Gourmet), qui doit toujours avancer, se d\u00e9placer, affronter, d\u00e9cider. Ses journ\u00e9es ne connaissent plus de moments priv\u00e9s. Il est profond\u00e9ment seul bien que toujours conseill\u00e9. Pierre Schoeller filme la vie concr\u00e8te d\u2019un minist\u00e8re, la charge colossale de travail que repr\u00e9sente le fonctionnement de la vie politique, \u00e0 travers le prisme des humeurs de Saint-Jean. Il souhaitait montrer le c\u00f4t\u00e9 physique et non c\u00e9r\u00e9bral de ce m\u00e9tier, l\u2019implication visc\u00e9rale du ministre, ses naus\u00e9es, ses ivresses, ses euphories ou col\u00e8res. La cam\u00e9ra reste au plus pr\u00e8s de son corps, humain, d\u00e9sirant et possiblement mortel. Il ne s\u2019agit pas tellement de montrer que le roi est nu, mais de <strong>saisir le c\u00f4t\u00e9 charnel et vivant du pouvoir<\/strong>. Le film m\u00e9lange r\u00e9alisme et surr\u00e9alisme\u00a0: affleurent parfois les r\u00eaves, cauchemars et fantasmes du ministre \u2013 telle cette sc\u00e8ne onirique, \u00e9trange et \u00e9rotique, o\u00f9 l\u2019on voit une femme nue, sur le tapis du minist\u00e8re, s\u2019engouffrer avec d\u00e9lectation dans la gueule grande ouverte d\u2019un crocodile. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: small;\">Tel est le questionnement sous-jacent \u00e0 ces films tr\u00e8s diff\u00e9rents\u00a0: <strong>reste-t-il aujourd\u2019hui des acteurs de la politique ou ne sont-ils que des pions\u00a0? Quelle est leur marge d\u2019action et leur prise sur le r\u00e9el\u00a0? Quels sujets sont-ils\u00a0?<\/strong><\/span><\/span><\/p>\n<p align=\"JUSTIFY\">\u00a0\u00a0 <span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: small;\"><em>Les marches du pouvoir<\/em> et <em>L\u2019exercice de l\u2019\u00c9tat<\/em> proc\u00e8dent \u00e0 <strong>une certaine r\u00e9habilitation du personnel politique <\/strong>\u2013 le propos n\u2019est pas de montrer qu\u2019ils sont \u00ab\u00a0tous pourris\u00a0\u00bb. Si les deux films ont leurs morts, les sacrifi\u00e9s du pouvoir, ce n\u2019est pas par calcul cynique ou mafieux, mais comme d\u00e9g\u00e2ts collat\u00e9raux, cons\u00e9quences de fautes commises par ces hommes politiques. Ces derniers ne sont pas d\u00e9peints comme des monstres de narcissisme, mus uniquement par leurs int\u00e9r\u00eats et ambitions personnels. M. Morris (Clooney) a une ambition citoyenne\u00a0: \u00ab\u00a0ma seule religion, c\u2019est la Constitution des \u00c9tats-Unis d\u2019Am\u00e9rique\u00a0\u00bb. Saint-Jean ne semble pas avoir de convictions profondes, mais a le sens de sa mission, et est \u00e9paul\u00e9 par un directeur de cabinet (Michel Blanc) qui fait couple avec l\u2019\u00c9tat, et est anim\u00e9 par un go\u00fbt v\u00e9ritable pour la chose publique \u2013 au point de conna\u00eetrepar c\u0153ur le discours d\u2019Andr\u00e9 Malraux lors de la panth\u00e9onisation de Jean Moulin. Tous aiment profond\u00e9ment faire de la politique, sont excit\u00e9s d\u2019\u00eatre l\u00e0 o\u00f9 les choses se d\u00e9cident, et poss\u00e9d\u00e9s par la fi\u00e8vre de l\u2019action. <\/span><\/span><\/p>\n<p align=\"JUSTIFY\">\u00a0\u00a0 <span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: small;\">N\u00e9anmoins, les deux films s\u2019ach\u00e8vent sur <\/span><\/span><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: small;\"><strong>les compromissions multiples qu\u2019exige l\u2019exercice du pouvoir\u00a0<\/strong><\/span><\/span><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: small;\">: M. Morris ne r\u00e9sistera pas au chantage\u00a0; le ministre Saint-Jean doit accepter la r\u00e9forme que Bercy lui impose. <\/span><\/span><em><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: small;\">\u00ab\u00a0La politique est une meurtrissure permanente\u00a0\u00bb, dit-il. <\/span><\/span><\/em><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: small;\">L\u2019engrenage du pouvoir l\u2019emporte\u00a0sur les personnages qui sont appel\u00e9s \u00e0 exercer ces fonctions \u2013 pas sans leur acquiescement, qu\u2019ils conc\u00e8dent par d\u00e9sir de sauver leur vocation politique. <\/span><\/span><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: small;\"><strong>L\u2019int\u00e9r\u00eat de ces films est de montrer la mati\u00e8re complexe du pouvoir, par-del\u00e0 l\u2019alternative simpliste entre id\u00e9alisme et r\u00e9alisme politique.<\/strong><\/span><\/span><\/p>\n<p align=\"JUSTIFY\"><span style=\"font-family: Calibri, sans-serif;\"><span style=\"font-size: small;\"><strong>Publi\u00e9 dans le N\u00b079 de Lacan Quotidien<\/strong><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: center;\" align=\"JUSTIFY\">\u00a0La mati\u00e8re complexe du pouvoir par Aur\u00e9lie Pfauwadel<\/p>\n<p align=\"JUSTIFY\">Deux films, cette semaine au cin\u00e9ma, nous offrent une plong\u00e9e dans les arcanes du pouvoir\u00a0: Les marches du pouvoir, de George Clonney, et\u00a0L\u2019exercice de l\u2019\u00c9tat de Pierre Schoeller. <\/p>\n","protected":false},"author":9,"featured_media":4899,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[301,17],"tags":[71,803,806,807,804,805],"class_list":["post-4898","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cinema","category-discretioncritique","tag-aurelie-pfauwadel","tag-george-clonney","tag-machiavel","tag-maurice-merleau-ponty","tag-pierre-schoeller","tag-pouvoir"],"_links":{"self":[{"href":"https:\/\/lacanquotidien.fr\/blog\/wp-json\/wp\/v2\/posts\/4898","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lacanquotidien.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lacanquotidien.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lacanquotidien.fr\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/lacanquotidien.fr\/blog\/wp-json\/wp\/v2\/comments?post=4898"}],"version-history":[{"count":3,"href":"https:\/\/lacanquotidien.fr\/blog\/wp-json\/wp\/v2\/posts\/4898\/revisions"}],"predecessor-version":[{"id":4902,"href":"https:\/\/lacanquotidien.fr\/blog\/wp-json\/wp\/v2\/posts\/4898\/revisions\/4902"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lacanquotidien.fr\/blog\/wp-json\/wp\/v2\/media\/4899"}],"wp:attachment":[{"href":"https:\/\/lacanquotidien.fr\/blog\/wp-json\/wp\/v2\/media?parent=4898"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lacanquotidien.fr\/blog\/wp-json\/wp\/v2\/categories?post=4898"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lacanquotidien.fr\/blog\/wp-json\/wp\/v2\/tags?post=4898"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}